{"id":20086,"date":"2024-08-14T16:31:34","date_gmt":"2024-08-14T22:31:34","guid":{"rendered":"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case.jpg"},"modified":"2024-08-14T16:32:51","modified_gmt":"2024-08-14T22:32:51","slug":"eye-glass-case","status":"inherit","type":"attachment","link":"https:\/\/www.prairiewoodbasketry.com\/index.php\/where-to-find-me\/eye-glass-case\/","title":{"rendered":"eye glass case"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0},"class_list":["post-20086","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>eye glass case &#8902; PrairieWood Basketry<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-scaled.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"eye glass case &#8902; PrairieWood Basketry\" \/>\n<meta property=\"og:description\" content=\"Eye Glass Case\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-scaled.jpg\" \/>\n<meta property=\"og:site_name\" content=\"PrairieWood Basketry\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/basketteacher\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-14T22:32:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-773x1030.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"773\" \/>\n\t<meta property=\"og:image:height\" content=\"1030\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-scaled.jpg\",\"url\":\"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-scaled.jpg\",\"name\":\"eye glass case &#8902; PrairieWood Basketry\",\"isPartOf\":{\"@id\":\"https:\/\/www.prairiewoodbasketry.com\/#website\"},\"datePublished\":\"2024-08-14T22:31:34+00:00\",\"dateModified\":\"2024-08-14T22:32:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-scaled.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-scaled.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-scaled.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.prairiewoodbasketry.com\/index.php\/frontpage\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Teaching Schedule\",\"item\":\"https:\/\/www.prairiewoodbasketry.com\/index.php\/where-to-find-me\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"eye glass case\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.prairiewoodbasketry.com\/#website\",\"url\":\"https:\/\/www.prairiewoodbasketry.com\/\",\"name\":\"PrairieWood Basketry\",\"description\":\"the Basket Teacher\",\"publisher\":{\"@id\":\"https:\/\/www.prairiewoodbasketry.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.prairiewoodbasketry.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.prairiewoodbasketry.com\/#organization\",\"name\":\"PrairieWood Basketry\",\"url\":\"https:\/\/www.prairiewoodbasketry.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.prairiewoodbasketry.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2018\/01\/RnB-LOGO-2.jpg\",\"contentUrl\":\"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2018\/01\/RnB-LOGO-2.jpg\",\"width\":1680,\"height\":1680,\"caption\":\"PrairieWood Basketry\"},\"image\":{\"@id\":\"https:\/\/www.prairiewoodbasketry.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/basketteacher\/\",\"https:\/\/www.instagram.com\/thebasketteacher\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"eye glass case &#8902; PrairieWood Basketry","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-scaled.jpg","og_locale":"en_US","og_type":"article","og_title":"eye glass case &#8902; PrairieWood Basketry","og_description":"Eye Glass Case","og_url":"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-scaled.jpg","og_site_name":"PrairieWood Basketry","article_publisher":"https:\/\/www.facebook.com\/basketteacher\/","article_modified_time":"2024-08-14T22:32:51+00:00","og_image":[{"width":773,"height":1030,"url":"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-773x1030.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-scaled.jpg","url":"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-scaled.jpg","name":"eye glass case &#8902; PrairieWood Basketry","isPartOf":{"@id":"https:\/\/www.prairiewoodbasketry.com\/#website"},"datePublished":"2024-08-14T22:31:34+00:00","dateModified":"2024-08-14T22:32:51+00:00","breadcrumb":{"@id":"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-scaled.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-scaled.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-scaled.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.prairiewoodbasketry.com\/index.php\/frontpage\/"},{"@type":"ListItem","position":2,"name":"Teaching Schedule","item":"https:\/\/www.prairiewoodbasketry.com\/index.php\/where-to-find-me\/"},{"@type":"ListItem","position":3,"name":"eye glass case"}]},{"@type":"WebSite","@id":"https:\/\/www.prairiewoodbasketry.com\/#website","url":"https:\/\/www.prairiewoodbasketry.com\/","name":"PrairieWood Basketry","description":"the Basket Teacher","publisher":{"@id":"https:\/\/www.prairiewoodbasketry.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.prairiewoodbasketry.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.prairiewoodbasketry.com\/#organization","name":"PrairieWood Basketry","url":"https:\/\/www.prairiewoodbasketry.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.prairiewoodbasketry.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2018\/01\/RnB-LOGO-2.jpg","contentUrl":"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2018\/01\/RnB-LOGO-2.jpg","width":1680,"height":1680,"caption":"PrairieWood Basketry"},"image":{"@id":"https:\/\/www.prairiewoodbasketry.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/basketteacher\/","https:\/\/www.instagram.com\/thebasketteacher\/"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-225x300.jpg 225w, https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-773x1030.jpg 773w, https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-60x80.jpg 60w, https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-1152x1536.jpg 1152w, https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-1536x2048.jpg 1536w, https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-1125x1500.jpg 1125w, https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-529x705.jpg 529w, https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-450x600.jpg 450w, https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-scaled.jpg 1920w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Eye Glass Case<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1920,"height":2560,"file":"2024\/08\/eye-glass-case-scaled.jpg","filesize":3711060,"sizes":{"medium":{"file":"eye-glass-case-225x300.jpg","width":225,"height":300,"filesize":72788,"mime_type":"image\/jpeg","source_url":"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-225x300.jpg"},"large":{"file":"eye-glass-case-773x1030.jpg","width":773,"height":1030,"filesize":689914,"mime_type":"image\/jpeg","source_url":"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-773x1030.jpg"},"thumbnail":{"file":"eye-glass-case-60x80.jpg","width":60,"height":80,"filesize":8074,"mime_type":"image\/jpeg","source_url":"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-60x80.jpg"},"1536x1536":{"file":"eye-glass-case-1152x1536.jpg","width":1152,"height":1536,"filesize":1460256,"mime_type":"image\/jpeg","source_url":"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-1152x1536.jpg"},"2048x2048":{"file":"eye-glass-case-1536x2048.jpg","width":1536,"height":2048,"filesize":2486631,"mime_type":"image\/jpeg","source_url":"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-1536x2048.jpg"},"widget":{"file":"eye-glass-case-36x36.jpg","width":36,"height":36,"filesize":3428,"mime_type":"image\/jpeg","source_url":"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-36x36.jpg"},"square":{"file":"eye-glass-case-180x180.jpg","width":180,"height":180,"filesize":41956,"mime_type":"image\/jpeg","source_url":"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-180x180.jpg"},"featured":{"file":"eye-glass-case-1500x430.jpg","width":1500,"height":430,"filesize":632104,"mime_type":"image\/jpeg","source_url":"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-1500x430.jpg"},"featured_large":{"file":"eye-glass-case-1500x630.jpg","width":1500,"height":630,"filesize":902858,"mime_type":"image\/jpeg","source_url":"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-1500x630.jpg"},"extra_large":{"file":"eye-glass-case-1125x1500.jpg","width":1125,"height":1500,"filesize":1401507,"mime_type":"image\/jpeg","source_url":"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-1125x1500.jpg"},"portfolio":{"file":"eye-glass-case-495x400.jpg","width":495,"height":400,"filesize":206247,"mime_type":"image\/jpeg","source_url":"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-495x400.jpg"},"portfolio_small":{"file":"eye-glass-case-260x185.jpg","width":260,"height":185,"filesize":60226,"mime_type":"image\/jpeg","source_url":"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-260x185.jpg"},"gallery":{"file":"eye-glass-case-845x684.jpg","width":845,"height":684,"filesize":554207,"mime_type":"image\/jpeg","source_url":"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-845x684.jpg"},"magazine":{"file":"eye-glass-case-710x375.jpg","width":710,"height":375,"filesize":283287,"mime_type":"image\/jpeg","source_url":"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-710x375.jpg"},"masonry":{"file":"eye-glass-case-529x705.jpg","width":529,"height":705,"filesize":339412,"mime_type":"image\/jpeg","source_url":"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-529x705.jpg"},"entry_with_sidebar":{"file":"eye-glass-case-845x321.jpg","width":845,"height":321,"filesize":292983,"mime_type":"image\/jpeg","source_url":"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-845x321.jpg"},"entry_without_sidebar":{"file":"eye-glass-case-1210x423.jpg","width":1210,"height":423,"filesize":518174,"mime_type":"image\/jpeg","source_url":"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-1210x423.jpg"},"shop_thumbnail":{"file":"eye-glass-case-120x120.jpg","width":120,"height":120,"filesize":20692,"mime_type":"image\/jpeg","source_url":"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-120x120.jpg"},"shop_catalog":{"file":"eye-glass-case-450x450.jpg","width":450,"height":450,"filesize":209320,"mime_type":"image\/jpeg","source_url":"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-450x450.jpg"},"shop_single":{"file":"eye-glass-case-450x600.jpg","width":450,"height":600,"filesize":249604,"mime_type":"image\/jpeg","source_url":"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-450x600.jpg"},"full":{"file":"eye-glass-case-scaled.jpg","width":1920,"height":2560,"mime_type":"image\/jpeg","source_url":"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-scaled.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"original_image":"eye-glass-case.jpg"},"post":14200,"source_url":"https:\/\/www.prairiewoodbasketry.com\/wp-content\/uploads\/2024\/08\/eye-glass-case-scaled.jpg","_links":{"self":[{"href":"https:\/\/www.prairiewoodbasketry.com\/index.php\/wp-json\/wp\/v2\/media\/20086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.prairiewoodbasketry.com\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.prairiewoodbasketry.com\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.prairiewoodbasketry.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.prairiewoodbasketry.com\/index.php\/wp-json\/wp\/v2\/comments?post=20086"}]}}